{"id":59,"date":"2022-04-07T13:15:48","date_gmt":"2022-04-07T12:15:48","guid":{"rendered":"https:\/\/vetcamp-project.eu\/?p=59"},"modified":"2022-04-07T13:15:48","modified_gmt":"2022-04-07T12:15:48","slug":"kick-off-meeting-in-schrobenhausen","status":"publish","type":"post","link":"https:\/\/vetcamp-project.eu\/es\/kick-off-meeting-in-schrobenhausen\/","title":{"rendered":"Reuni\u00f3n inaugural en Schrobenhausen"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-59-2674493720]\" href=\"https:\/\/vetcamp-project.eu\/wp-content\/uploads\/2022\/04\/kick-off-sob-1-1024x768.jpg\" target=\"_self\"><img width=\"2016\" height=\"1512\" src=\"https:\/\/vetcamp-project.eu\/wp-content\/uploads\/2022\/04\/kick-off-sob-1.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"kick-off-sob-1\" decoding=\"async\" title=\"kick-off-sob-1\" loading=\"lazy\" srcset=\"https:\/\/vetcamp-project.eu\/wp-content\/uploads\/2022\/04\/kick-off-sob-1.jpg 2016w, https:\/\/vetcamp-project.eu\/wp-content\/uploads\/2022\/04\/kick-off-sob-1-300x225.jpg 300w, https:\/\/vetcamp-project.eu\/wp-content\/uploads\/2022\/04\/kick-off-sob-1-1024x768.jpg 1024w, https:\/\/vetcamp-project.eu\/wp-content\/uploads\/2022\/04\/kick-off-sob-1-768x576.jpg 768w, https:\/\/vetcamp-project.eu\/wp-content\/uploads\/2022\/04\/kick-off-sob-1-1536x1152.jpg 1536w, https:\/\/vetcamp-project.eu\/wp-content\/uploads\/2022\/04\/kick-off-sob-1-16x12.jpg 16w\" sizes=\"(max-width: 2016px) 100vw, 2016px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Los d\u00edas 21 y 22 de febrero de 2022, nos reunimos todos en la sede de la Universidad Popular de Schrobenhausen, en Schrobenhausen, Baviera, para el proyecto \"VETCAMP - Green VET Online Campus\". El objetivo de la reuni\u00f3n era llegar a un acuerdo sobre el proyecto y debatir las cuestiones clave relacionadas con la primera fase de su ejecuci\u00f3n. Cada socio present\u00f3 su organizaci\u00f3n y la experiencia especial que aporta al proyecto.<\/p>\n<p>Tambi\u00e9n repasamos las actividades del proyecto y las funciones de los socios en la producci\u00f3n de resultados y acordamos un plan de trabajo renovado, as\u00ed como las pr\u00f3ximas etapas de la implementaci\u00f3n del proyecto VETCAMP. La pr\u00f3xima reuni\u00f3n del proyecto tendr\u00e1 lugar en Portugal en diciembre.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"author":1,"featured_media":60,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/vetcamp-project.eu\/es\/wp-json\/wp\/v2\/posts\/59"}],"collection":[{"href":"https:\/\/vetcamp-project.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vetcamp-project.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vetcamp-project.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vetcamp-project.eu\/es\/wp-json\/wp\/v2\/comments?post=59"}],"version-history":[{"count":0,"href":"https:\/\/vetcamp-project.eu\/es\/wp-json\/wp\/v2\/posts\/59\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vetcamp-project.eu\/es\/wp-json\/wp\/v2\/media\/60"}],"wp:attachment":[{"href":"https:\/\/vetcamp-project.eu\/es\/wp-json\/wp\/v2\/media?parent=59"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vetcamp-project.eu\/es\/wp-json\/wp\/v2\/categories?post=59"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vetcamp-project.eu\/es\/wp-json\/wp\/v2\/tags?post=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}